{"id":132,"date":"2014-03-25T08:43:52","date_gmt":"2014-03-25T08:43:52","guid":{"rendered":"http:\/\/recordersforsale.com\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg"},"modified":"2014-03-25T08:43:52","modified_gmt":"2014-03-25T08:43:52","slug":"05-kobliczek-praetorius-soprano-440-recordersforsale-com-03","status":"inherit","type":"attachment","link":"https:\/\/recordersforsale.com\/sold\/kobliczek-renaissance-consort-440hz\/05-kobliczek-praetorius-soprano-440-recordersforsale-com-03\/","title":{"rendered":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-132","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/ag895n-28","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"462\" src=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=260%2C462&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=260%2C462&amp;ssl=1 260w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=640%2C1138&amp;ssl=1 640w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" data-attachment-id=\"132\" data-permalink=\"https:\/\/recordersforsale.com\/sold\/kobliczek-renaissance-consort-440hz\/05-kobliczek-praetorius-soprano-440-recordersforsale-com-03\/\" data-orig-file=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=720%2C1280&amp;ssl=1\" data-orig-size=\"720,1280\" data-comments-opened=\"0\" data-image-title=\"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=640%2C1138&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":720,"height":1280,"file":"2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg","sizes":{"thumbnail":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-165x165.jpg","width":165,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=165%2C165&ssl=1"},"medium":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-260x462.jpg","width":260,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=260%2C462&ssl=1"},"large":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-640x1138.jpg","width":640,"height":1138,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=640%2C1138&ssl=1"},"img-square-big":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-720x970.jpg","width":720,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=720%2C970&ssl=1"},"img-landscape-big":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-720x728.jpg","width":720,"height":728,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=720%2C728&ssl=1"},"img-square":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-700x700.jpg","width":700,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=700%2C700&ssl=1"},"img-portrait":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-700x933.jpg","width":700,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=700%2C933&ssl=1"},"img-landscape":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03-700x525.jpg","width":700,"height":525,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?resize=700%2C525&ssl=1"},"full":{"file":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=720%2C1280&ssl=1","width":720,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg?fit=720%2C1280&ssl=1"}},"image_meta":{"aperture":2.8,"credit":"","camera":"Canon IXUS 130","caption":"","created_timestamp":1395676751,"copyright":"","focal_length":"5","iso":"80","shutter_speed":"0.016666666666667","title":"","orientation":1}},"post":75,"source_url":"https:\/\/recordersforsale.com\/sold\/wp-content\/uploads\/2014\/03\/05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg","filename":"05-Kobliczek-Praetorius-Soprano-440-recordersforsale-com-03.jpg","filesize":714299,"_links":{"self":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/media\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/comments?post=132"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":75,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/posts\/75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}