{"id":11190,"date":"2022-04-03T21:11:03","date_gmt":"2022-04-03T19:11:03","guid":{"rendered":"https:\/\/recordersforsale.com\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg"},"modified":"2022-04-03T21:11:03","modified_gmt":"2022-04-03T19:11:03","slug":"aesthe-soprano-boudreau-recorders-for-sale-com-05","status":"inherit","type":"attachment","link":"https:\/\/recordersforsale.com\/sold\/aesthe-soprano-boudreau\/aesthe-soprano-boudreau-recorders-for-sale-com-05\/","title":{"rendered":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-11190","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/ag895n-2Uu","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"151\" src=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=260%2C151&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?w=1669&amp;ssl=1 1669w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=260%2C151&amp;ssl=1 260w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=640%2C372&amp;ssl=1 640w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=768%2C446&amp;ssl=1 768w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=1536%2C893&amp;ssl=1 1536w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" data-attachment-id=\"11190\" data-permalink=\"https:\/\/recordersforsale.com\/sold\/aesthe-soprano-boudreau\/aesthe-soprano-boudreau-recorders-for-sale-com-05\/\" data-orig-file=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=1669%2C970&amp;ssl=1\" data-orig-size=\"1669,970\" data-comments-opened=\"0\" data-image-title=\"Aesthe-soprano-Boudreau-recorders-for-sale-com-05\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=640%2C372&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1669,"height":970,"file":"2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg","sizes":{"medium":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-260x151.jpg","width":260,"height":151,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=260%2C151&ssl=1"},"large":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-640x372.jpg","width":640,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=640%2C372&ssl=1"},"thumbnail":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-165x165.jpg","width":165,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=165%2C165&ssl=1"},"medium_large":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-768x446.jpg","width":768,"height":446,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=700%2C407&ssl=1"},"1536x1536":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-1536x893.jpg","width":1536,"height":893,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=1536%2C893&ssl=1"},"img-square-big":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-970x970.jpg","width":970,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=970%2C970&ssl=1"},"img-portrait-big":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-970x970.jpg","width":970,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=970%2C970&ssl=1"},"img-landscape-big":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-970x728.jpg","width":970,"height":728,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=970%2C728&ssl=1"},"img-square":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-700x700.jpg","width":700,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=700%2C700&ssl=1"},"img-portrait":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-700x933.jpg","width":700,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=700%2C933&ssl=1"},"img-landscape":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05-700x525.jpg","width":700,"height":525,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?resize=700%2C525&ssl=1"},"full":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=1669%2C970&ssl=1","width":1669,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg?fit=1669%2C970&ssl=1"}},"image_meta":{"aperture":"0","credit":"\"                                                                                                                                                                                                                                                               \"","camera":"X-E3","caption":"","created_timestamp":"0","copyright":"","focal_length":"28","iso":"640","shutter_speed":"0.003125","title":"","orientation":"1","keywords":[]}},"post":11184,"source_url":"https:\/\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg","filename":"Aesthe-soprano-Boudreau-recorders-for-sale-com-05.jpg","filesize":378868,"_links":{"self":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/media\/11190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/comments?post=11190"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":11184,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/posts\/11184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}