{"id":11186,"date":"2022-04-03T21:10:51","date_gmt":"2022-04-03T19:10:51","guid":{"rendered":"https:\/\/recordersforsale.com\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg"},"modified":"2022-04-03T21:10:51","modified_gmt":"2022-04-03T19:10:51","slug":"aesthe-soprano-boudreau-recorders-for-sale-com-01","status":"inherit","type":"attachment","link":"https:\/\/recordersforsale.com\/sold\/aesthe-soprano-boudreau\/aesthe-soprano-boudreau-recorders-for-sale-com-01\/","title":{"rendered":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-11186","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/ag895n-2Uq","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"149\" src=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=260%2C149&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?w=1698&amp;ssl=1 1698w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=260%2C149&amp;ssl=1 260w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=640%2C366&amp;ssl=1 640w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=768%2C439&amp;ssl=1 768w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=1536%2C877&amp;ssl=1 1536w, https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" data-attachment-id=\"11186\" data-permalink=\"https:\/\/recordersforsale.com\/sold\/aesthe-soprano-boudreau\/aesthe-soprano-boudreau-recorders-for-sale-com-01\/\" data-orig-file=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=1698%2C970&amp;ssl=1\" data-orig-size=\"1698,970\" data-comments-opened=\"0\" data-image-title=\"Aesthe-soprano-Boudreau-recorders-for-sale-com-01\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=640%2C366&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1698,"height":970,"file":"2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg","sizes":{"medium":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-260x149.jpg","width":260,"height":149,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=260%2C149&ssl=1"},"large":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-640x366.jpg","width":640,"height":366,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=640%2C366&ssl=1"},"thumbnail":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-165x165.jpg","width":165,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=165%2C165&ssl=1"},"medium_large":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-768x439.jpg","width":768,"height":439,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=700%2C400&ssl=1"},"1536x1536":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-1536x877.jpg","width":1536,"height":877,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=1536%2C877&ssl=1"},"img-square-big":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-970x970.jpg","width":970,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=970%2C970&ssl=1"},"img-portrait-big":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-970x970.jpg","width":970,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=970%2C970&ssl=1"},"img-landscape-big":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-970x728.jpg","width":970,"height":728,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=970%2C728&ssl=1"},"img-square":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-700x700.jpg","width":700,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=700%2C700&ssl=1"},"img-portrait":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-700x933.jpg","width":700,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=700%2C933&ssl=1"},"img-landscape":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01-700x525.jpg","width":700,"height":525,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?resize=700%2C525&ssl=1"},"full":{"file":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=1698%2C970&ssl=1","width":1698,"height":970,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg?fit=1698%2C970&ssl=1"}},"image_meta":{"aperture":"0","credit":"\"                                                                                                                                                                                                                                                               \"","camera":"X-E3","caption":"","created_timestamp":"0","copyright":"","focal_length":"28","iso":"640","shutter_speed":"0.003125","title":"","orientation":"1","keywords":[]}},"post":11184,"source_url":"https:\/\/recordersforsale.com\/sold\/wp-content\/uploads\/2022\/04\/Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg","filename":"Aesthe-soprano-Boudreau-recorders-for-sale-com-01.jpg","filesize":365075,"_links":{"self":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/media\/11186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/comments?post=11186"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":11184,"href":"https:\/\/recordersforsale.com\/sold\/wp-json\/wp\/v2\/posts\/11184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}